{"id":105,"count":22,"description":"","link":"https:\/\/www.diytelavivguide.com\/blog\/tag\/rap","name":"rap","slug":"rap","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>rap Archives | DIY Tel Aviv<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diytelavivguide.com\/blog\/tag\/rap\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"rap Archives | DIY Tel Aviv\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diytelavivguide.com\/blog\/tag\/rap\" \/>\n<meta property=\"og:site_name\" content=\"DIY Tel Aviv\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diytelavivguide.com\/blog\/wp-content\/uploads\/2015\/01\/cropped-thelogo-11-e1496476245812.png\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tag\\\/rap\",\"url\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tag\\\/rap\",\"name\":\"rap Archives | DIY Tel Aviv\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tag\\\/rap#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tag\\\/rap#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"rap\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/\",\"name\":\"DIY Tel Aviv\",\"description\":\"Your Alternative City Guide\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/#organization\",\"name\":\"DIY Tel Aviv\",\"url\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/thelogo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/thelogo-1.png\",\"width\":1416,\"height\":1406,\"caption\":\"DIY Tel Aviv\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diytelaviv\",\"https:\\\/\\\/www.instagram.com\\\/diytelaviv\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"rap Archives | DIY Tel Aviv","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diytelavivguide.com\/blog\/tag\/rap","og_locale":"en_US","og_type":"article","og_title":"rap Archives | DIY Tel Aviv","og_url":"https:\/\/www.diytelavivguide.com\/blog\/tag\/rap","og_site_name":"DIY Tel Aviv","og_image":[{"width":200,"height":200,"url":"https:\/\/www.diytelavivguide.com\/blog\/wp-content\/uploads\/2015\/01\/cropped-thelogo-11-e1496476245812.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.diytelavivguide.com\/blog\/tag\/rap","url":"https:\/\/www.diytelavivguide.com\/blog\/tag\/rap","name":"rap Archives | DIY Tel Aviv","isPartOf":{"@id":"https:\/\/www.diytelavivguide.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.diytelavivguide.com\/blog\/tag\/rap#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.diytelavivguide.com\/blog\/tag\/rap#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.diytelavivguide.com\/blog"},{"@type":"ListItem","position":2,"name":"rap"}]},{"@type":"WebSite","@id":"https:\/\/www.diytelavivguide.com\/blog\/#website","url":"https:\/\/www.diytelavivguide.com\/blog\/","name":"DIY Tel Aviv","description":"Your Alternative City Guide","publisher":{"@id":"https:\/\/www.diytelavivguide.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diytelavivguide.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.diytelavivguide.com\/blog\/#organization","name":"DIY Tel Aviv","url":"https:\/\/www.diytelavivguide.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.diytelavivguide.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.diytelavivguide.com\/blog\/wp-content\/uploads\/2015\/01\/thelogo-1.png","contentUrl":"https:\/\/www.diytelavivguide.com\/blog\/wp-content\/uploads\/2015\/01\/thelogo-1.png","width":1416,"height":1406,"caption":"DIY Tel Aviv"},"image":{"@id":"https:\/\/www.diytelavivguide.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diytelaviv","https:\/\/www.instagram.com\/diytelaviv\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.diytelavivguide.com\/blog\/wp-json\/wp\/v2\/tags\/105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diytelavivguide.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.diytelavivguide.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.diytelavivguide.com\/blog\/wp-json\/wp\/v2\/posts?tags=105"},{"href":"https:\/\/www.diytelavivguide.com\/blog\/wp-json\/wp\/v2\/pages?tags=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}