{"id":2223,"date":"2011-06-04T10:00:37","date_gmt":"2011-06-04T08:00:37","guid":{"rendered":"http:\/\/www.diytelavivguide.com\/blog\/?p=3174"},"modified":"2011-06-03T13:05:57","modified_gmt":"2011-06-03T11:05:57","slug":"huge-demo-tonight-say-yes-to-a-palestinian-state","status":"publish","type":"post","link":"https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state","title":{"rendered":"Huge demo tonight &#8211; say YES to a Palestinian state"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-2224\" title=\"activizem\" src=\"https:\/\/www.diytelavivguide.com\/blog\/wp-content\/uploads\/2011\/06\/activizem-300x300.jpg\" alt=\"\" width=\"180\" height=\"180\" \/> Tonight at 19:00 at Rabin Square there will be a massive (hopefully) demo in favour of the two state solution and saying YES to having a Palestinian state according to the 1967 borders. Come show that liar that he may be able to fool Obama (actually, he can&#8217;t) but not us. Meet at the square and then set off on a march to that big, popular area outside the art museum where there will be speeches and things. Come along, bring your friends.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tonight at 19:00 at Rabin Square there will be a massive (hopefully) demo in favour of the two state solution and saying YES to having a Palestinian state according to&#8230;<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[18,83,59],"class_list":["post-2223","post","type-post","status-publish","format-standard","hentry","category-tel-aviv-politics-and-activism","tag-activism","tag-demo","tag-politics"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Huge demo tonight - say YES to a Palestinian state | DIY Tel Aviv<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Huge demo tonight - say YES to a Palestinian state | DIY Tel Aviv\" \/>\n<meta property=\"og:description\" content=\"Tonight at 19:00 at Rabin Square there will be a massive (hopefully) demo in favour of the two state solution and saying YES to having a Palestinian state according to...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state\" \/>\n<meta property=\"og:site_name\" content=\"DIY Tel Aviv\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diytelaviv\" \/>\n<meta property=\"article:published_time\" content=\"2011-06-04T08:00:37+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.diytelavivguide.com\/blog\/wp-content\/uploads\/2011\/06\/activizem-300x300.jpg\" \/>\n<meta name=\"author\" content=\"DIY Tel Aviv\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"DIY Tel Aviv\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tel-aviv-politics-and-activism\\\/huge-demo-tonight-say-yes-to-a-palestinian-state#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tel-aviv-politics-and-activism\\\/huge-demo-tonight-say-yes-to-a-palestinian-state\"},\"author\":{\"name\":\"DIY Tel Aviv\",\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/#\\\/schema\\\/person\\\/41d39c42c86ef54449b25170057a9a95\"},\"headline\":\"Huge demo tonight &#8211; say YES to a Palestinian state\",\"datePublished\":\"2011-06-04T08:00:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tel-aviv-politics-and-activism\\\/huge-demo-tonight-say-yes-to-a-palestinian-state\"},\"wordCount\":91,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tel-aviv-politics-and-activism\\\/huge-demo-tonight-say-yes-to-a-palestinian-state#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/activizem-300x300.jpg\",\"keywords\":[\"activism\",\"demo\",\"politics\"],\"articleSection\":[\"Tel Aviv Politics and Activism\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tel-aviv-politics-and-activism\\\/huge-demo-tonight-say-yes-to-a-palestinian-state#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tel-aviv-politics-and-activism\\\/huge-demo-tonight-say-yes-to-a-palestinian-state\",\"url\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tel-aviv-politics-and-activism\\\/huge-demo-tonight-say-yes-to-a-palestinian-state\",\"name\":\"Huge demo tonight - say YES to a Palestinian state | DIY Tel Aviv\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tel-aviv-politics-and-activism\\\/huge-demo-tonight-say-yes-to-a-palestinian-state#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tel-aviv-politics-and-activism\\\/huge-demo-tonight-say-yes-to-a-palestinian-state#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/activizem-300x300.jpg\",\"datePublished\":\"2011-06-04T08:00:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tel-aviv-politics-and-activism\\\/huge-demo-tonight-say-yes-to-a-palestinian-state#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tel-aviv-politics-and-activism\\\/huge-demo-tonight-say-yes-to-a-palestinian-state\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tel-aviv-politics-and-activism\\\/huge-demo-tonight-say-yes-to-a-palestinian-state#primaryimage\",\"url\":\"http:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/activizem-300x300.jpg\",\"contentUrl\":\"http:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/activizem-300x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/tel-aviv-politics-and-activism\\\/huge-demo-tonight-say-yes-to-a-palestinian-state#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tel Aviv Politics and Activism\",\"item\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/category\\\/tel-aviv-politics-and-activism\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Huge demo tonight &#8211; say YES to a Palestinian state\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/\",\"name\":\"DIY Tel Aviv\",\"description\":\"Your Alternative City Guide\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/#organization\",\"name\":\"DIY Tel Aviv\",\"url\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/thelogo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/thelogo-1.png\",\"width\":1416,\"height\":1406,\"caption\":\"DIY Tel Aviv\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diytelaviv\",\"https:\\\/\\\/www.instagram.com\\\/diytelaviv\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diytelavivguide.com\\\/blog\\\/#\\\/schema\\\/person\\\/41d39c42c86ef54449b25170057a9a95\",\"name\":\"DIY Tel Aviv\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/65ff152d81150d9cd863b20a56bc3f41efe66e38acbd767f20157f3e8add4069?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/65ff152d81150d9cd863b20a56bc3f41efe66e38acbd767f20157f3e8add4069?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/65ff152d81150d9cd863b20a56bc3f41efe66e38acbd767f20157f3e8add4069?s=96&d=mm&r=g\",\"caption\":\"DIY Tel Aviv\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Huge demo tonight - say YES to a Palestinian state | DIY Tel Aviv","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state","og_locale":"en_US","og_type":"article","og_title":"Huge demo tonight - say YES to a Palestinian state | DIY Tel Aviv","og_description":"Tonight at 19:00 at Rabin Square there will be a massive (hopefully) demo in favour of the two state solution and saying YES to having a Palestinian state according to...","og_url":"https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state","og_site_name":"DIY Tel Aviv","article_publisher":"https:\/\/www.facebook.com\/diytelaviv","article_published_time":"2011-06-04T08:00:37+00:00","og_image":[{"url":"http:\/\/www.diytelavivguide.com\/blog\/wp-content\/uploads\/2011\/06\/activizem-300x300.jpg","type":"","width":"","height":""}],"author":"DIY Tel Aviv","twitter_card":"summary_large_image","twitter_misc":{"Written by":"DIY Tel Aviv"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state#article","isPartOf":{"@id":"https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state"},"author":{"name":"DIY Tel Aviv","@id":"https:\/\/www.diytelavivguide.com\/blog\/#\/schema\/person\/41d39c42c86ef54449b25170057a9a95"},"headline":"Huge demo tonight &#8211; say YES to a Palestinian state","datePublished":"2011-06-04T08:00:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state"},"wordCount":91,"commentCount":0,"publisher":{"@id":"https:\/\/www.diytelavivguide.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state#primaryimage"},"thumbnailUrl":"http:\/\/www.diytelavivguide.com\/blog\/wp-content\/uploads\/2011\/06\/activizem-300x300.jpg","keywords":["activism","demo","politics"],"articleSection":["Tel Aviv Politics and Activism"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state","url":"https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state","name":"Huge demo tonight - say YES to a Palestinian state | DIY Tel Aviv","isPartOf":{"@id":"https:\/\/www.diytelavivguide.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state#primaryimage"},"image":{"@id":"https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state#primaryimage"},"thumbnailUrl":"http:\/\/www.diytelavivguide.com\/blog\/wp-content\/uploads\/2011\/06\/activizem-300x300.jpg","datePublished":"2011-06-04T08:00:37+00:00","breadcrumb":{"@id":"https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state#primaryimage","url":"http:\/\/www.diytelavivguide.com\/blog\/wp-content\/uploads\/2011\/06\/activizem-300x300.jpg","contentUrl":"http:\/\/www.diytelavivguide.com\/blog\/wp-content\/uploads\/2011\/06\/activizem-300x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.diytelavivguide.com\/blog\/tel-aviv-politics-and-activism\/huge-demo-tonight-say-yes-to-a-palestinian-state#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.diytelavivguide.com\/blog"},{"@type":"ListItem","position":2,"name":"Tel Aviv Politics and Activism","item":"https:\/\/www.diytelavivguide.com\/blog\/category\/tel-aviv-politics-and-activism"},{"@type":"ListItem","position":3,"name":"Huge demo tonight &#8211; say YES to a Palestinian state"}]},{"@type":"WebSite","@id":"https:\/\/www.diytelavivguide.com\/blog\/#website","url":"https:\/\/www.diytelavivguide.com\/blog\/","name":"DIY Tel Aviv","description":"Your Alternative City Guide","publisher":{"@id":"https:\/\/www.diytelavivguide.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diytelavivguide.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.diytelavivguide.com\/blog\/#organization","name":"DIY Tel Aviv","url":"https:\/\/www.diytelavivguide.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.diytelavivguide.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.diytelavivguide.com\/blog\/wp-content\/uploads\/2015\/01\/thelogo-1.png","contentUrl":"https:\/\/www.diytelavivguide.com\/blog\/wp-content\/uploads\/2015\/01\/thelogo-1.png","width":1416,"height":1406,"caption":"DIY Tel Aviv"},"image":{"@id":"https:\/\/www.diytelavivguide.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diytelaviv","https:\/\/www.instagram.com\/diytelaviv\/"]},{"@type":"Person","@id":"https:\/\/www.diytelavivguide.com\/blog\/#\/schema\/person\/41d39c42c86ef54449b25170057a9a95","name":"DIY Tel Aviv","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/65ff152d81150d9cd863b20a56bc3f41efe66e38acbd767f20157f3e8add4069?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/65ff152d81150d9cd863b20a56bc3f41efe66e38acbd767f20157f3e8add4069?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/65ff152d81150d9cd863b20a56bc3f41efe66e38acbd767f20157f3e8add4069?s=96&d=mm&r=g","caption":"DIY Tel Aviv"}}]}},"_links":{"self":[{"href":"https:\/\/www.diytelavivguide.com\/blog\/wp-json\/wp\/v2\/posts\/2223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diytelavivguide.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diytelavivguide.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diytelavivguide.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diytelavivguide.com\/blog\/wp-json\/wp\/v2\/comments?post=2223"}],"version-history":[{"count":2,"href":"https:\/\/www.diytelavivguide.com\/blog\/wp-json\/wp\/v2\/posts\/2223\/revisions"}],"predecessor-version":[{"id":2226,"href":"https:\/\/www.diytelavivguide.com\/blog\/wp-json\/wp\/v2\/posts\/2223\/revisions\/2226"}],"wp:attachment":[{"href":"https:\/\/www.diytelavivguide.com\/blog\/wp-json\/wp\/v2\/media?parent=2223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diytelavivguide.com\/blog\/wp-json\/wp\/v2\/categories?post=2223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diytelavivguide.com\/blog\/wp-json\/wp\/v2\/tags?post=2223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}